{"id":3104,"date":"2018-03-02T09:44:15","date_gmt":"2018-03-02T08:44:15","guid":{"rendered":"https:\/\/www.gotha3.de\/forschungsblog\/?post_type=tribe_events&#038;p=3104"},"modified":"2018-10-02T12:49:12","modified_gmt":"2018-10-02T10:49:12","slug":"9-kartenwochen-meridian-gotha","status":"publish","type":"tribe_events","link":"https:\/\/www.gotha3.de\/forschungsblog\/event\/9-kartenwochen-meridian-gotha","title":{"rendered":"9. Gothaer Kartenwochen \u201eMeridian Gotha. Zur Triangulation und Vermessung Th\u00fcringens um 1800\u201c"},"content":{"rendered":"<p>Unter dem Titel \u201eMeridian Gotha. Zur Triangulation und Vermessung Th\u00fcringens um 1800\u201c veranstalten die Forschungsbibliothek Gotha und das Forschungszentrum Gotha der Universit\u00e4t Erfurt, diesmal gemeinsam mit dem Sammlungs- und Forschungsverbund Gotha, die \u201e9. Gothaer Kartenwochen\u201c, die sich der geod\u00e4tischen und kartographischen Tradition Gothas widmen.<\/p>\n<p>Dieses Jahr thematisieren sie die Triangulation und Vermessung der th\u00fcringischen Lande unter Herzog Ernst II. und seinen Nachfolgern bis zur K\u00f6niglich-Preu\u00dfischen Landesaufnahme um 1851-1855. Die Grundlage f\u00fcr eine erste Triangulation und Landesaufnahme wurde bereits mit dem Projekt zur Gradmessung unter Herzog Ernst II. und dem Astronomen Franz Xaver Freiherr von Zach und der astronomischen Bestimmung des Meridians der Sternwarte auf dem Seeberg ab 1792 gelegt. Erstmalig wird die Ausstellung einzigartige Funde aus den Best\u00e4nden der Sammlung Perthes und der Forschungsbibliothek Gotha sowie der Stiftung Schloss Friedenstein zur Vermessungsgeschichte Th\u00fcringens zusammenf\u00fchren und der \u00d6ffentlichkeit pr\u00e4sentieren.<\/p>\n<p>W\u00e4hrend der Laufzeit der Ausstellung findet ein abwechslungsreiches <a href=\"https:\/\/www.gotha3.de\/forschungsblog\/wp-content\/uploads\/2018\/08\/Flyer_Kartenwochen_2018_web.pdf\"><strong>Begleitprogramm<\/strong><\/a> statt.<\/p>\n<p><strong>Weitere Informationen \/ Kontakt:<\/strong><br \/>\nDr. des. Matthias Rekow<br \/>\nTel.: +49 361 737-5564<br \/>\nE-Mail: <a href=\"mailto:matthias.rekow@uni-erfurt.de\">matthias.rekow@uni-erfurt.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter dem Titel \u201eMeridian Gotha. Zur Triangulation und Vermessung Th\u00fcringens um 1800\u201c veranstalten die Forschungsbibliothek Gotha und das Forschungszentrum Gotha der Universit\u00e4t Erfurt, diesmal gemeinsam mit dem Sammlungs- und Forschungsverbund Gotha, die \u201e9. Gothaer Kartenwochen\u201c, die sich der geod\u00e4tischen und kartographischen Tradition Gothas widmen. Dieses Jahr thematisieren sie die Triangulation und Vermessung der th\u00fcringischen Lande &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.gotha3.de\/forschungsblog\/event\/9-kartenwochen-meridian-gotha\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e9. Gothaer Kartenwochen \u201eMeridian Gotha. Zur Triangulation und Vermessung Th\u00fcringens um 1800\u201c\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"tags":[80,217,91,111,112,220,243,233,221,159,216,225,242],"tribe_events_cat":[199],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tribe_events\/3104"}],"collection":[{"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/comments?post=3104"}],"version-history":[{"count":11,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tribe_events\/3104\/revisions"}],"predecessor-version":[{"id":3468,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tribe_events\/3104\/revisions\/3468"}],"wp:attachment":[{"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/media?parent=3104"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tags?post=3104"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.gotha3.de\/forschungsblog\/wp-json\/wp\/v2\/tribe_events_cat?post=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}